{"id":4199,"date":"2026-07-15T13:13:10","date_gmt":"2026-07-15T13:13:10","guid":{"rendered":"https:\/\/newz.com.mx\/index.php\/2026\/07\/15\/empresarios-suman-voces-contra-el-presunto-tirador-de-la-via-atlixcayotl\/"},"modified":"2026-07-15T19:13:12","modified_gmt":"2026-07-15T19:13:12","slug":"empresarios-suman-voces-contra-el-presunto-tirador-de-la-via-atlixcayotl","status":"publish","type":"post","link":"https:\/\/newz.com.mx\/index.php\/2026\/07\/15\/empresarios-suman-voces-contra-el-presunto-tirador-de-la-via-atlixcayotl\/","title":{"rendered":"Empresarios suman voces contra el presunto tirador de la V\u00eda Atlixc\u00e1yotl"},"content":{"rendered":"<p>El gobernador de Puebla, Alejandro Armenta, revel\u00f3 que varios empresarios se han acercado a su gobierno para aportar nuevos testimonios sobre Rafael N., el tipo se\u00f1alado como responsable de los ataques armados en la V\u00eda Atlixc\u00e1yotl. <\/p>\n<p>Esto lo cont\u00f3 en una rueda de prensa desde la Ciudad de M\u00e9xico, donde explic\u00f3 que uno de esos empresarios, que prefiri\u00f3 mantenerse en el anonimato, presentar\u00e1 formalmente su testimonio ante la Fiscal\u00eda General del Estado (FGE). La idea es que esta info se sume a la carpeta de investigaci\u00f3n y ayude a aclarar el caso.<\/p>\n<p>Armenta dej\u00f3 claro que ser\u00e1 la Fiscal\u00eda la que decida qu\u00e9 tan valiosa es esta informaci\u00f3n y si se abren nuevas l\u00edneas de investigaci\u00f3n. Adem\u00e1s, destac\u00f3 que la colaboraci\u00f3n de ciudadanos y empresarios es clave para que todo se resuelva conforme a derecho.<\/p>\n<p>Esta declaraci\u00f3n lleg\u00f3 justo un d\u00eda despu\u00e9s de la detenci\u00f3n de Rafael N., quien sigue bajo investigaci\u00f3n por los ataques contra automovilistas en la V\u00eda Atlixc\u00e1yotl. La Fiscal\u00eda poblana contin\u00faa integrando el caso para llevarlo a fondo. <\/p>\n<p>As\u00ed que, mientras las autoridades trabajan, la participaci\u00f3n de la sociedad se vuelve un punto clave para que la justicia no se quede en palabras.<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/Diario_Cambio\/status\/2077462232481345859\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador de Puebla, Alejandro Armenta, revel\u00f3 que varios empresarios se han acercado a su gobierno para aportar nuevos testimonios sobre Rafael N., el tipo se\u00f1alado como responsable de los ataques armados en la V\u00eda Atlixc\u00e1yotl. Esto lo cont\u00f3 en una rueda de prensa desde la Ciudad de M\u00e9xico, donde explic\u00f3 que uno de esos&#8230;<\/p>\n<div class=\"btnReadMore pt20 bButton\"><a href=\"https:\/\/newz.com.mx\/index.php\/2026\/07\/15\/empresarios-suman-voces-contra-el-presunto-tirador-de-la-via-atlixcayotl\/\">READ MORE<\/a><\/div>\n","protected":false},"author":1,"featured_media":4198,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local"],"_links":{"self":[{"href":"https:\/\/newz.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/4199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newz.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newz.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newz.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newz.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=4199"}],"version-history":[{"count":1,"href":"https:\/\/newz.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/4199\/revisions"}],"predecessor-version":[{"id":4200,"href":"https:\/\/newz.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/4199\/revisions\/4200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newz.com.mx\/index.php\/wp-json\/wp\/v2\/media\/4198"}],"wp:attachment":[{"href":"https:\/\/newz.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=4199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newz.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=4199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newz.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=4199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}